{"id":13629,"date":"2021-12-09T14:29:56","date_gmt":"2021-12-09T14:29:56","guid":{"rendered":"https:\/\/szechenyilevelezes.abtk.hu\/uncategorized\/szechenyi-ferenc-134\/"},"modified":"2026-05-10T14:14:39","modified_gmt":"2026-05-10T14:14:39","slug":"szechenyi-ferenc-134","status":"publish","type":"post","link":"https:\/\/szechenyilevelezes.abtk.hu\/en\/csalad-en\/szechenyi-ferenc-134\/","title":{"rendered":"Ferenc Sz\u00e9ch\u00e9nyi"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><em>Geschrieben in Athen den 18<sup>ten<\/sup> J\u00e4ner<\/em><a href=\"#_ftn1\">[1]<\/a><a href=\"#_edn1\"><u>[a]<\/u><\/a><\/p>\n\n\n\n<p>Sie wissen, Mein lieber guter Vater, aus meinen Briefen,<a href=\"#_edn2\">[b]<\/a> da\u00df ich den 4<sup>ten<\/sup> dieses Monath von hier weggereist\u2019 bin, um bis zu dem Thal Tempe<a href=\"#_edn3\">[c]<\/a> in Thessalien zu gelangen. Vorgestern bin ich von meiner erm\u00fcdenden Course zuruckgekommen \u2013 und \u00e4nderte meinen Plan bis in die Gegend des Olymps zu gehen, da das Wetter zu schlecht und der Schnee zu gewaltig gewesen ist \u2013 ich begrenzte daher meinen Ausflug bis Zeitorin,<a href=\"#_edn4\">[d]<\/a> eine kleine t\u00fcrksche Stadt, hinter Thermopyle, und kam zur See zwischen Beotien und der langen Insel Eubea, jetzt Negropont,<a href=\"#_edn5\">[e]<\/a> wieder hier zuruck. In der hin Reise gieng mein Weg \u00fcber Nepropont, von wo ich Ihnen geschrieben habe,<a href=\"#_edn6\">[f]<\/a> dan mit einem Umweg \u00fcber den Berg Cytheron<a href=\"#_edn7\">[g]<\/a> nach Thebe Livadia,<a href=\"#_edn8\">[h]<\/a> dem Berg Parnass,<a href=\"#_edn9\">[i]<\/a> und das Schlachtfeld von Cheronea<a href=\"#_edn10\">[j]<\/a> nach dem Pass von Thermopyle selbst wo ich einen Tag blieb und endlich nach Zeitorin. Das Wetter war, f\u00fcr die t\u00fcrksche Art zu reisen, nicht eben gar zu h\u00fcbsch \u2013 den<a href=\"#_ftn2\">[2]<\/a> es ist nicht angenehm auf schlechten Pferden, \u00fcber Felsen und in tiefem Schnee und Koth von Sonnen Aufgang bis zur Sinkenden Sonne bei kaltem und feuchtem Wetter zu reisen \u2013 und dan in durchl\u00f6cherten H\u00e4usern zu \u00fcbernachten. Im ganzen aber, nur einige Tage abgerechnet waren brauchbar, und ich hab\u2019 aus ganzer Seele den Genu\u00df geno\u00dfen in einer Gegend 14 Tage zugebracht zu haben, in welcher jede Kleinigkeit angenehme Errinnerungen weckt, und wo das Land selbst, und die ewig wechselnden Scenen dem Reisenden das Vergn\u00fcgen und diese gute Stimmung v\u00f6llig g\u00f6nnen, dessen er Bedarf, um auf alles das zu verge\u00dfen, was man entbehren mu\u00df \u2013 und was wirklich in das Weitl\u00e4ufige gehet. \u2013 In meiner HinReise hat sich nichts merkw\u00fcrdiges f\u00fcr mich zugetragen, auser, da\u00df ich so gl\u00fccklich war 3 alte Griechen die, unschuldiger Weise nach dem Gef\u00e4ngni\u00df geschleppt wurden, in Negropont durch meine Intercession bei dem Ibrahim Pasha, zu befreien. Ich halte nicht viel auf die Griechen, und denke auch von denen 3 alten Gesellen die ich aus dem kalten uncomfortablen Kerker herausgekriegt habe, nicht viel gutes und r\u00fchmliches, dennoch haben sie mich ger\u00fchrt, als sie weinend und in einer verdammt schlechten und abgeh\u00e4rmten Condition sich bei mir bedankten. Wie \u00fcberhaupt da die Menschen sich gegenseitig betr\u00fcgen, und endlich von denen M\u00e4chtigeren mit F\u00fc\u00dfen getretten werden \u2013 ist eine lange Epistel dar\u00fcber zu schreiben. \u2013 Von Zeitorin sind <em>wir<\/em>,<a href=\"#_ftn3\">[3]<\/a> den,<sup>2<\/sup> Sie wissen aus meinen Briefen, da\u00df ich mit M<sup>r<\/sup><a href=\"#_ftn4\">[4]<\/a> Wilson<a href=\"#_edn11\">[k]<\/a> diese Reise unternahm, zu einem Hafen, um eine barque zu nehmen und l\u00e4ngst denen K\u00fcsten der Insel Negropont fortzu segeln, und in Marathon oder Cap Colonna auszuschiffen. Dieses Vorhaben war gewagt, den<sup>2<\/sup> manche Schiffer brauchen 3 bis 4 Wochen um diese Fahrt zu vollenden, da in dieser hoher Zeit der S\u00fcd Wind der herrschende zu sein pflegt; indessen, wissen Sie, lieber Vater, da\u00df das Gl\u00fcck k\u00fchn und dreist zu machen pflegt \u2013 Wir trugen kein Bedenken, und waren auch so favorisirt von denen Elementen, da\u00df wir in 60 Stunden in dem Hafen von <em>Marathon<\/em>,<sup>3<\/sup> wo die Perser landeten, aus unsern Both gestiegen sind.<a href=\"#_edn12\">[l]<\/a> Einige unangenehme Aventuren h\u00e4tten dennoch, diese Fahrt. beinahe auf eine zu lange Zeit verl\u00e4ngert. Wir mietheten unser kleines Schif mit 3 albernen furchtsamen Griechen nur bis Negropont wo wir, aussteigen mu\u00dften um die Courrente abzuwarten, die in diesem Canal Ebbe und Fluth beobachten. Zum Ungl\u00fcck war kein anders Schif zu bekommen, und durchaus keine Pferde. Unsere Ungeduld hingegen ein wenig zu \u00fcbertrieben. Wie soll man aber nicht ein wenig <em>gelangweilt<\/em><sup>3<\/sup> sein, wenn man 12 Tage auf Brod und ger\u00f6stete alte Hahnen reducirt ist, und endlich Wein zu trinken und warm zu e\u00dfen, sich gewaltig sehnt? Die Schifer also von dem Hafen Stilida<a href=\"#_edn14\">[m]<\/a> wo wir uns embarquirten, und welcher Ort Sie auf keiner Karte finden k\u00f6nnen, wurden \u00e0 force de largent,<a href=\"#_ftn5\">[5]<\/a> das hei\u00dft um 200 Piaster gen\u00f6thiget, nur weiter zu fahren, wie wohl sie in der See, die sie zu durchfahren hatten, fr\u00fcher noch nie gewesen sind. &#8211; Ich erhob mich zum Piloten und wir segelten um 2 Uhr Nachmittag, den mir immer merkw\u00fcrdigen 13<sup>ten<\/sup> mit einem heftigen sch\u00f6nen Wind aus dem Hafen von Negropont. Ich wollte bis zur Sinkenden Sonne fortfahren, und in einem kleinen Dorf welches wir in der N\u00e4he des Strandes vermutheten, ruhig \u00fcbernachten, den<sup>2<\/sup> die Nacht durchzufahren schien mir nicht rathsam, da der Himmel dunkel gew\u00f6lkt war, und dieser Canal voll von Felsen und Sandb\u00e4nken ist. Vor dem Dorf Paleo Casteo<a href=\"#_edn15\">[n]<\/a> <em>wo ich mein Nachtlager aufzuschlagen gesonnen war<\/em><a href=\"#_ftn7\">[6]<\/a> sind die Ruinen von Eretria,<a href=\"#_edn16\">[o]<\/a> wo die Griechen sich so lang gegen des Xerxes Leute vertheitigten<a href=\"#_ftn8\">[7]<\/a> \u2013 Diese wollte ich noch fr\u00fcher, als es dunkel ward, ansehen, und von da zu Fu\u00df nach dem besagten Dorf gehen. Der Wind war so stark und die Wellen so klein, da\u00df wir mehr als 8 englische Meilen in einer Stunde machten, Ich berechnete es ganz genau \u2013 und es war eine sch\u00f6ne combination! den<sup>2<\/sup> nachdem wir 2 und \u00be Stunden rasch von dannen segelten erblicken wir Eretrias t\u00fcchtige Ruinen \u2013 und lenkten gegen das Ufer \u2013 kaum war die\u00df kleine Maneuvre vollendet, als einer der Schifs Leute ganz nahe vor uns, einen steinernen Damm im Wasser erblickte und mit Gewalt die Segeln auseinader schnitt. Die Gegenwart des Geistes dieses Griechen rettete uns da von einem completen Schifbruch, und wir waren mit einem starken Sto\u00df um<a href=\"#_ftn9\">[8]<\/a> die K\u00f6pfe alle auf dem Boden vor die\u00dfmal quitt. Die Mauer aber, war ein Molo von dem alten Eretria! Wir sind wieder gegen die Tiefe. Die Sonne gieng indessen ganz roth in denen Wogen unter und der Wind wurde heftig, der gew\u00f6hnlich damals k\u00f6mt, wenn man ihn am wenigsten braucht. Nach einer Fahrt von einer halben Stunde im Dunkeln und unbekannten Meere wagten wir uns wieder, mit einem kleinen Segelchen nicht gr\u00f6\u00dfer wie ein Schnupftuch gegen das Ufer \u2013 und waren <em>so gl\u00fccklich<\/em><sup>3<\/sup> geradetzu auf eine Groupe Felsen zuzusteuern, und davon mit bla\u00dfen Gesichtern abzuprallen. Der Wind war so stark, da\u00df er unser kleines Fahrzeug, best\u00e4ndig gegen diesen unangenehmen Felsen, der sich unter dem Wasser lang fortzog mit Macht zutrieb \u2013 Sie wissen lieber Vater was f\u00fcr eine confusion in einem solchen Augenblick entstehet. Das war auch bei uns der Fall, und wir schrien in mehreren Sprachen aus vollen Leibes Kr\u00e4ften. Die Ruder wurden genommen, und nach einer l\u00e4rmenden Arbeit von 2 Stunden hinter einem Felsenblock der von Wind sch\u00fctzte, Anker gelegt, der NB<a href=\"#_ftn10\">[9]<\/a> 24 Pfund schwer war. Das Fahrzeug erhielt mehrere Wunden und hielt Wasser; aussteigen konnte man nicht \u2014 und ich mu\u00dfte mit meinem Engl\u00e4nder, 12 alberne Stunden, in dieser l\u00e4cherlichen Laage zubringen den andern Morgen wurde auf die andere Seite gefahren, und um 1 Uhr Nachmittag landeten wir auf gut Gl\u00fcck in einem Hafen, der aus Zufall, der von Marathon gewesen ist. \u2013 Da blieb ich den und den andern Tag in einem alten verfallenen Kloster, und ritt am dritten Tag auf einen excellenten Esel, und meinem <em>ungrischen<\/em><sup>3<\/sup> Sattel in diese Residens. Fand Landschulz<a href=\"#_edn17\">[p]<\/a> und Ender<a href=\"#_edn18\">[q]<\/a> die gegen alle Elemente gek\u00e4mpft haben, und nicht weniger als 21 Tage von Smyrna hierher gebraucht haben! \u2014<\/p>\n\n\n\n<p>Nun bleibe ich noch 2 Wochen hier und werde dan<sup>2<\/sup> \u00fcber Corynth Sparta<a href=\"#_edn19\">[r]<\/a> ect ect ect nach Patras reisen, wo ich mich den 20<sup>ten<\/sup> Februar f\u00fcr Malta einschiffen will. Dort werde ich die Quarantaine zubringen, und endlich, wenn es Gott will, in Neapel gegen den 15<sup>ten<\/sup> April ausschiffen.<\/p>\n\n\n\n<p>Kein Geld habe ich noch nicht aufgenommen, werde es aber bald. Wie und wie viel, wei\u00df ich noch nicht. Ich vermeide aber jede unn\u00f6thige Ausgabe das versichere ich Sie aufs bestimteste, Lieber Vater;<\/p>\n\n\n\n<p>Meine Gesundheit ist so so \u2014 und ich lebe in einer ewigen und ununterbrochen Unruhe. Vieleicht mu\u00df es so sein, und das tr\u00f6stet mich ungemein. Wenn Sie nur lieber Vater und meine theuere Mutter gesund sind und gl\u00fccklich, und wenn Sie glauben, da\u00df ich nichts so sehr, wie Sie beide, in dieser Welt liebe, und da\u00df ich mit meinem Herz und meinem Gewissen, Gottlob, in ziemlich guter Ordnung stehe.<\/p>\n\n\n\n<p>Geben Sie mir nun den Seegen und denken Sie manchmal an mich Stepherl<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p><a href=\"#_ftnref1\">[1]<\/a> Sz\u00e9chenyi\u2019s underlining with wavy line.<\/p>\n\n\n\n<p><a href=\"#_ftnref2\">[2]<\/a> Instead of denn.<\/p>\n\n\n\n<p><a href=\"#_ftnref3\">[3]<\/a> Sz\u00e9chenyi\u2019s underlining with straight line.<\/p>\n\n\n\n<p><a href=\"#_ftnref4\">[4]<\/a> Mister<\/p>\n\n\n\n<p><a href=\"#_ftnref5\">[5]<\/a> French: only for money.<\/p>\n\n\n\n<p><a href=\"#_ftnref7\">[6]<\/a> Inserted afterwards.<\/p>\n\n\n\n<p><a href=\"#_ftnref8\">[7]<\/a> Instead of verteidigten.<\/p>\n\n\n\n<p><a href=\"#_ftnref9\">[8]<\/a> One word deleted.<\/p>\n\n\n\n<p><a href=\"#_ftnref10\">[9]<\/a> Nota bene. Latin: note well.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p><a href=\"#_ednref1\">[a]<\/a> The letter was written based on its content in 1819.<\/p>\n\n\n\n<p><a href=\"#_ednref2\">[b]<\/a> See the previous letter.<\/p>\n\n\n\n<p><a href=\"#_ednref3\">[c]<\/a> In the north-east of Greece is the Tempe River and its valley, and to the north is Mount Olympos.<\/p>\n\n\n\n<p><a href=\"#_ednref4\">[d]<\/a> The Turkish name of Lancia, a town in the vicinity of the Strait of Thermopylae.<\/p>\n\n\n\n<p><a href=\"#_ednref5\">[e]<\/a> Negroponte, old name for Euboea, an island in the Aegean Sea belonging to Greece.<\/p>\n\n\n\n<p><a href=\"#_ednref6\">[f]<\/a> See the letter of 4 January 1819. <\/p>\n\n\n\n<p><a href=\"#_ednref7\">[g]<\/a> A mountain near Thebes, northwest of Athens.<\/p>\n\n\n\n<p><a href=\"#_ednref8\">[h]<\/a> Greek town west of Thebes.<\/p>\n\n\n\n<p><a href=\"#_ednref9\">[i]<\/a> Mount Parnassus, west of Livadia.<\/p>\n\n\n\n<p><a href=\"#_ednref10\">[j]<\/a> Cheronen, in the vicinity of Livadia. The Greeks were defeated there by the Macedonian King Philip II in 338 BCE and lost their independence.<\/p>\n\n\n\n<p><a href=\"#_ednref11\">[k]<\/a> The physician returning from East India.<\/p>\n\n\n\n<p><a href=\"#_ednref12\">[l]<\/a> Marathon lies close to the east coast of Attica, famous for the Athenian victory over the Persians under Miltiades in 490 BCE. The site of the battle could only be determined after excavations by the Greeks in the 1990s.\u00a0<\/p>\n\n\n\n<p><a href=\"#_ednref14\">[m]<\/a> Port east of Lancia.<\/p>\n\n\n\n<p><a href=\"#_ednref15\">[n]<\/a> Eretria otherwise known as Paleo Casteo village.<\/p>\n\n\n\n<p><a href=\"#_ednref16\">[o]<\/a> A village on the west coast of the island of Euboea, in the port of Parthmus, destroyed by the Persians in 490 BCE and its inhabitants taken captive. Later rebuilt a little further down the coast, under the name Eretoia.<\/p>\n\n\n\n<p><a href=\"#_ednref17\">[p]<\/a> Julius Landschulz was a philologist and teacher of classical languages and literacy, formerly tutor to Count J\u00f3zsef Zichy. Sz\u00e9chenyi&#8217;s companion during his journey to the East.<\/p>\n\n\n\n<p><a href=\"#_ednref18\">[q]<\/a> Johann Ender (1793\u20131854) an Austrian painter who accompanied Sz\u00e9chenyi on his journey to the East.<\/p>\n\n\n\n<p><a href=\"#_ednref19\">[r]<\/a> The capital of Sparta or Laconia on the right bank of the Eurotas.<\/p>\n\n\n\n<p>Recommended reference:<\/p>\n\n\n\n<p>Istv\u00e1n Sz\u00e9chenyi to Ferenc Sz\u00e9ch\u00e9nyi, Athens, 18 January 1819. Edited and annotated by Szilvia Czinege. Published in Correspondence of Istv\u00e1n Sz\u00e9chenyi. Digital edition. Edited by Szilvia Czinege and Zolt\u00e1n F\u00f3nagy. https:\/\/szechenyilevelezes.abtk.hu\/ Abbreviation for further references: SzIL-Digit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>He reports on the stops on his tour from Athens. The weather was not right, but he enjoyed the journey. He was touched by the three Greeks whose release he had helped to secure with<br \/>\nthe pasha. During their journey they ate monotonous food and survived a shipwreck. He will stay for two weeks. He has not yet taken out any money, but he does not know how or how much, but he\u2019ll try to avoid unnecessary expenses.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3403,3370,3438],"tags":[3544,3417],"language":[3416],"addressee":[3411],"place_of_writing":[4496],"qualification":[3383],"place_of_keeping":[4503],"place_of_publication":[4504],"class_list":["post-13629","post","type-post","status-publish","format-standard","hentry","category-szechenyi_ferenc-en","category-csalad-en","category-the-traveller","tag-money","tag-travel","language-german","addressee-ferenc-szechenyi","place_of_writing-athens","qualification-original","place_of_keeping-mnl-ol-p-623-a-i-9-no-44-13-en","place_of_publication-zichy-270-273-en"],"_links":{"self":[{"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/posts\/13629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/comments?post=13629"}],"version-history":[{"count":2,"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/posts\/13629\/revisions"}],"predecessor-version":[{"id":13633,"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/posts\/13629\/revisions\/13633"}],"wp:attachment":[{"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/media?parent=13629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/categories?post=13629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/tags?post=13629"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/language?post=13629"},{"taxonomy":"addressee","embeddable":true,"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/addressee?post=13629"},{"taxonomy":"place_of_writing","embeddable":true,"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/place_of_writing?post=13629"},{"taxonomy":"qualification","embeddable":true,"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/qualification?post=13629"},{"taxonomy":"place_of_keeping","embeddable":true,"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/place_of_keeping?post=13629"},{"taxonomy":"place_of_publication","embeddable":true,"href":"https:\/\/szechenyilevelezes.abtk.hu\/en\/wp-json\/wp\/v2\/place_of_publication?post=13629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}